{"id":6528,"date":"2013-07-02T08:29:35","date_gmt":"2013-07-02T11:29:35","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/?p=6528"},"modified":"2013-07-02T08:42:12","modified_gmt":"2013-07-02T11:42:12","slug":"anderson-silva-acredita-que-nao-tem-chances-contra-jon-jones-acho-que-nao-vou-vencer","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/2013\/07\/02\/anderson-silva-acredita-que-nao-tem-chances-contra-jon-jones-acho-que-nao-vou-vencer\/","title":{"rendered":"Anderson Silva acredita que n\u00e3o tem chances contra Jon Jones: Acho que n\u00e3o vou vencer!"},"content":{"rendered":"<figure id=\"attachment_5366\" aria-describedby=\"caption-attachment-5366\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2013\/05\/andersoncorinthians.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5366 \" src=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2013\/05\/andersoncorinthians.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/a><figcaption id=\"caption-attachment-5366\" class=\"wp-caption-text\">Anderson acredita que tem poucas chances contra Jones - Divulga\u00e7\u00e3o UFC<\/figcaption><\/figure>\n<p>Muito tem se especulado em uma superluta entre o brasileiro Anderson Silva, campe\u00e3o peso m\u00e9dio do UFC contra o americano Jon Jones, campe\u00e3o meio pesado da organiza\u00e7\u00e3o.<\/p>\n<p>Para o brasileiro, suas chances de poder vencer este sonhado combate pelos f\u00e3s \u00e9 muito pequena.<\/p>\n<p>&#8220;Em sua categoria, Jon Jones \u00e9 o melhor. Se enfrent\u00e1-lo, acho que eu n\u00e3o vou vencer.<\/p>\n<p>Jon Jones \u00e9 diferente. Ele \u00e9 largo. Ele \u00e9 jovem. Mas na luta eu me vejo em Jon Jones, vejo eu mesmo de muito tempo atr\u00e1s. Ele \u00e9 muito inteligente.<\/p>\n<p>N\u00e3o sei. Na minha opini\u00e3o, tenho mais experi\u00eancia que o Jon Jones, mas essa \u00e9 a \u00fanica vantagem.&#8221; disse Anderson em entrevista ao site americano MMA Fighting.<\/p>\n<p>O brasileiro que enfrenta o americano Chris Weidman neste fim de semana est\u00e1 focado para manter sua invencibilidade de 16 lutas no UFC.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muito tem se especulado em uma superluta entre o brasileiro Anderson Silva, campe\u00e3o peso m\u00e9dio do UFC contra o americano Jon Jones, campe\u00e3o meio pesado <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/2013\/07\/02\/anderson-silva-acredita-que-nao-tem-chances-contra-jon-jones-acho-que-nao-vou-vencer\/\">leia mais<\/a><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[22,50,85],"class_list":["post-6528","post","type-post","status-publish","format-standard","hentry","category-principal","tag-anderson-silva","tag-chris-weidman","tag-jon-jones"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6rqUQ-1Hi","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts\/6528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/comments?post=6528"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts\/6528\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/media?parent=6528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/categories?post=6528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/tags?post=6528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}