{"id":2710,"date":"2013-01-12T05:19:10","date_gmt":"2013-01-12T07:19:10","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/?p=2710"},"modified":"2013-01-12T05:19:10","modified_gmt":"2013-01-12T07:19:10","slug":"especial-vai-acontecer-veja-a-pesagem-do-strikeforce-deste-sabado-marquardt-vs-saffiedine","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/2013\/01\/12\/especial-vai-acontecer-veja-a-pesagem-do-strikeforce-deste-sabado-marquardt-vs-saffiedine\/","title":{"rendered":"Especial Vai Acontecer &#8211; Veja a pesagem do Strikeforce deste s\u00e1bado &#8211; Marquardt vs Saffiedine"},"content":{"rendered":"<figure id=\"attachment_2711\" aria-describedby=\"caption-attachment-2711\" style=\"width: 576px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2013\/01\/strikeforcejacare.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2711 \" src=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2013\/01\/strikeforcejacare.jpg\" alt=\"\" width=\"576\" height=\"384\" \/><\/a><figcaption id=\"caption-attachment-2711\" class=\"wp-caption-text\">Veja pesagem do evento com participa\u00e7\u00e3o de Ronaldo Jacar\u00e9 - Foto - Divulga\u00e7\u00e3o Showtime Sports <\/figcaption><\/figure>\n<p>Veja a pesagem do Strikeforce deste s\u00e1bado, evento que acontece em Oklahoma, nos Estados Unidos.<\/p>\n<p>Contando com v\u00e1rios brasileiros no card, como Ronaldo Jacar\u00e9, Roger Gracie, Jorge Gurgel e Adriano Martins, o evento ser\u00e1 o \u00faltimo da companhia.<\/p>\n<p>O Strikeforce foi vendido para a Zuffa, empresa que controla o UFC, e n\u00e3o teve seu contrato renovado com a emissora de televis\u00e3o americana, Showtime Sports.<\/p>\n<p>Sendo assim, o evento fecha as portas neste s\u00e1bado.<\/p>\n<p>Al\u00e9m dos brasileiros, quatro grandes combates chamam a aten\u00e7\u00e3o do p\u00fablico.<\/p>\n<p>Os americanos Daniel Cormier e Josh Barnett, al\u00e9m do arm\u00eanio Gegard Mousasi, far\u00e3o participa\u00e7\u00f5es no evento.<\/p>\n<p>E a luta principal do evento, o combate entre o ex-lutador do UFC, Nate Marquardt, que j\u00e1 enfrentou Anderson Silva, contra Tarec Saffiedine.<\/p>\n<p style=\"text-align: center\"><strong>Assista os melhores momentos da pesagem do evento:<\/strong><\/p>\n<p style=\"text-align: center\"><strong>[yframe url=&#8217;http:\/\/www.youtube.com\/watch?v=3KD_-1qSJ18&#8242;]<\/strong><\/p>\n<p style=\"text-align: center\">\n<p style=\"text-align: center\"><strong> <\/strong><\/p>\n<div style=\"text-align: center\"><strong>Siga nosso Twitter &#8211; www.twitter.com\/BrMassami e comente sobre esta not\u00edcia!<\/strong><\/div>\n<div style=\"text-align: center\"><strong><br \/>\n<\/strong><\/div>\n<div style=\"text-align: center\"><strong>Siga nosso Facebook \u00a0&#8211; http:\/\/www.facebook.com\/PlanetaOctogono<\/strong><\/div>\n<p style=\"text-align: center\">\n<p style=\"text-align: center\"><strong><br \/>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veja a pesagem do Strikeforce deste s\u00e1bado, evento que acontece em Oklahoma, nos Estados Unidos. Contando com v\u00e1rios brasileiros no card, como Ronaldo Jacar\u00e9, Roger <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/2013\/01\/12\/especial-vai-acontecer-veja-a-pesagem-do-strikeforce-deste-sabado-marquardt-vs-saffiedine\/\">leia mais<\/a><\/p>\n","protected":false},"author":33,"featured_media":2711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[9],"tags":[],"class_list":["post-2710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vai-acontecer"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2013\/01\/strikeforcejacare.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6rqUQ-HI","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts\/2710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/comments?post=2710"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts\/2710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/media\/2711"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/media?parent=2710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/categories?post=2710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/tags?post=2710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}