{"id":2632,"date":"2013-01-06T20:50:18","date_gmt":"2013-01-06T22:50:18","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/?p=2632"},"modified":"2013-01-06T20:50:18","modified_gmt":"2013-01-06T22:50:18","slug":"ronaldo-jacare-renova-com-empresa-tercerizada-do-ufc-e-pode-lutar-no-ultimate","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/2013\/01\/06\/ronaldo-jacare-renova-com-empresa-tercerizada-do-ufc-e-pode-lutar-no-ultimate\/","title":{"rendered":"Ronaldo Jacar\u00e9 renova com empresa tercerizada do UFC e pode lutar no Ultimate"},"content":{"rendered":"<figure id=\"attachment_2633\" aria-describedby=\"caption-attachment-2633\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2013\/01\/RonaldoSouza_Headshot.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2633\" src=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2013\/01\/RonaldoSouza_Headshot.png\" alt=\"\" width=\"500\" height=\"325\" \/><\/a><figcaption id=\"caption-attachment-2633\" class=\"wp-caption-text\">Lutador ir\u00e1 fazer \u00faltima luta no Strikeforce - Foto - Divulga\u00e7\u00e3o Strikeforce<\/figcaption><\/figure>\n<p>Uma \u00f3tima not\u00edcia para\u00a0os f\u00e3s\u00a0brasileiros.\u00a0Uma semana antes de\u00a0sua pr\u00f3xima luta, o ex-campe\u00e3o dos m\u00e9dios\u00a0do Strikeforce,\u00a0Ronaldo\u00a0Jacar\u00e9 e\u00a0assinou\u00a0um novo acordo com\u00a0Forza, LLC.<\/p>\n<p>Essa empresa &#8220;Forza LLC&#8221;, \u00e9 a empresa respons\u00e1vel pelos contratos do Strikeforce, no entanto, o Strikeforce cessar\u00e1 as opera\u00e7\u00f5es a partir da pr\u00f3xima semana.<\/p>\n<p>Gilberto Faria disse que a esperan\u00e7a \u00e9 que assim que o Strikeforce &#8220;fechar as portas&#8221;, o contrato ser\u00e1 transferido para o UFC, que tem sido o caso de muitos outros lutadores que tinham contrato com o Strikeforce.<\/p>\n<p>A prorroga\u00e7\u00e3o do contrato, com certeza, pode ser um voto de confian\u00e7a da Zuffa.<\/p>\n<p>Jacar\u00e9\u00a0tem 20 lutas no seu cartel com 16 vit\u00f3rias, 3 derrotas e um combate sem resultado, e tem sido\u00a0considerado um dos\u00a0melhores talentos\u00a0da divis\u00e3o dos m\u00e9dios.<\/p>\n<p>Al\u00e9m de ostentar um \u00f3timo curr\u00edculo no MMA, o brasileiro tem grande destaque com conquistas em mundiais de Jiu\u00a0Jitsu e\u00a0do ADCC.<\/p>\n<p>No dia 12 de janeiro,\u00a0ele vai enfrentar\u00a0Ed\u00a0Herman\u00a0no\u00a0\u00faltimo\u00a0evento\u00a0do Strikeforce.<\/p>\n<p style=\"text-align: center\"><strong>Conhe\u00e7a Ronaldo Jacar\u00e9:<\/strong><\/p>\n<p style=\"text-align: center\"><strong>[yframe url=&#8217;http:\/\/www.youtube.com\/watch?v=z9vTJUxpT48&#8242;]<\/strong><\/p>\n<p style=\"text-align: center\">\n<p style=\"text-align: center\"><strong> <\/strong><\/p>\n<div style=\"text-align: center\"><strong>Siga nosso Twitter &#8211; www.twitter.com\/BrMassami e comente sobre esta not\u00edcia!<\/strong><\/div>\n<div style=\"text-align: center\"><strong><br \/>\n<\/strong><\/div>\n<div style=\"text-align: center\"><strong>Siga nosso Facebook \u00a0&#8211; http:\/\/www.facebook.com\/PlanetaOctogono<\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uma \u00f3tima not\u00edcia para\u00a0os f\u00e3s\u00a0brasileiros.\u00a0Uma semana antes de\u00a0sua pr\u00f3xima luta, o ex-campe\u00e3o dos m\u00e9dios\u00a0do Strikeforce,\u00a0Ronaldo\u00a0Jacar\u00e9 e\u00a0assinou\u00a0um novo acordo com\u00a0Forza, LLC. Essa empresa &#8220;Forza LLC&#8221;, \u00e9 <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/2013\/01\/06\/ronaldo-jacare-renova-com-empresa-tercerizada-do-ufc-e-pode-lutar-no-ultimate\/\">leia mais<\/a><\/p>\n","protected":false},"author":33,"featured_media":2633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-2632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2013\/01\/RonaldoSouza_Headshot.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6rqUQ-Gs","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts\/2632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/comments?post=2632"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts\/2632\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/media\/2633"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/media?parent=2632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/categories?post=2632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/tags?post=2632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}