{"id":23065,"date":"2023-05-24T07:08:40","date_gmt":"2023-05-24T10:08:40","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/?p=23065"},"modified":"2023-05-24T07:08:40","modified_gmt":"2023-05-24T10:08:40","slug":"buscando-recorde-ksw-volta-a-estadio-de-futebol-na-polonia-em-junho","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/2023\/05\/24\/buscando-recorde-ksw-volta-a-estadio-de-futebol-na-polonia-em-junho\/","title":{"rendered":"Buscando recorde, KSW volta a est\u00e1dio de futebol na Pol\u00f4nia em junho"},"content":{"rendered":"<figure id=\"attachment_21930\" aria-describedby=\"caption-attachment-21930\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2017\/05\/IMG_20170528_043952_148.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-21930\" src=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2017\/05\/IMG_20170528_043952_148-1024x576.jpg\" alt=\"\" width=\"640\" height=\"360\" srcset=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2017\/05\/IMG_20170528_043952_148.jpg 1024w, https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2017\/05\/IMG_20170528_043952_148-300x169.jpg 300w, https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2017\/05\/IMG_20170528_043952_148-768x432.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><figcaption id=\"caption-attachment-21930\" class=\"wp-caption-text\">Em busca de novo record, KSW \u00e9 o segundo evento mais visto da hist\u00f3ria do MMA &#8211; Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>O maior evento de MMA da Europa, o KSW quer fazer hist\u00f3ria mais uma vez.<\/p>\n<p>Em busca de fazer um novo recorde, a organiza\u00e7\u00e3o polonesa est\u00e1 com planos ambiciosos.<\/p>\n<p>Ap\u00f3s um hiato de quase 6 anos, o evento vai voltar a realizar um show em um est\u00e1dio de futebol.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=sco6boelfq8&#038;pp=ygUPa3N3IDM5IG90d2FyY2ll<\/p>\n<p>No dia 3 de junho, o PGE Narodowy que j\u00e1 recebeu a empresa em 2017, volta a ter o MMA como atra\u00e7\u00e3o.<\/p>\n<p>E desta vez com transmiss\u00e3o para o Brasil, j\u00e1 que desde o fim de 2022, o Canal Combate possui os direitos de exibi\u00e7\u00e3o para o territ\u00f3rio nacional.<\/p>\n<p>Apostando em estrelas locais e as lendas Mamed Khalidov al\u00e9m do &#8220;Homem Mais Forte de Mundo&#8221; por cinco vezes, Mariusz Pudzianowski, o KSW busca quebrar o pr\u00f3prio recorde estabelecido pela organiza\u00e7\u00e3o ao atingir mais de 57 mil ingressos vendidos, se tornando o segundo maior evento da hist\u00f3ria do MMA.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=qgFAlgw9qpg<\/p>\n<p>O card vai ter a presen\u00e7a brasileira de Wellerson Martins que vai desafiar o campe\u00e3o peso galo Jakub Wiklacz pelo t\u00edtulo da categoria.<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=iL8SoSgkPng<\/p>\n<p>Caso consiga vencer, Wellerson pode ser o primeiro brasileiro a conquistar o t\u00edtulo da organiza\u00e7\u00e3o neste peso, j\u00e1 que Ariane Lipski, Kl\u00e9ber Koike e Fernando Santo Forte j\u00e1 foram campe\u00f5es do KSW em outras categorias.<\/p>\n<p><iframe loading=\"lazy\" title=\"KSW Free Fight: Ariane Lipski vs Diana Belbita at KSW 39\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/tSL4vXhfmgo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O maior evento de MMA da Europa, o KSW quer fazer hist\u00f3ria mais uma vez. Em busca de fazer um novo recorde, a organiza\u00e7\u00e3o polonesa <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/2023\/05\/24\/buscando-recorde-ksw-volta-a-estadio-de-futebol-na-polonia-em-junho\/\">leia mais<\/a><\/p>\n","protected":false},"author":33,"featured_media":21930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[137,1839,624,424,1840],"class_list":["post-23065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal","tag-ksw","tag-ksw-colosseum-2","tag-mamed-khalidov","tag-mariusz-pudzianowski","tag-wellerson-martins"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2017\/05\/IMG_20170528_043952_148.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6rqUQ-601","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts\/23065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/comments?post=23065"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts\/23065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/media\/21930"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/media?parent=23065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/categories?post=23065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/tags?post=23065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}