{"id":21126,"date":"2016-03-21T09:21:54","date_gmt":"2016-03-21T12:21:54","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/?p=21126"},"modified":"2016-03-21T09:21:54","modified_gmt":"2016-03-21T12:21:54","slug":"jose-aldo-volta-a-pedir-revanche-contra-conor-mcgregor-no-ufc","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/2016\/03\/21\/jose-aldo-volta-a-pedir-revanche-contra-conor-mcgregor-no-ufc\/","title":{"rendered":"Jos\u00e9 Aldo volta a pedir revanche contra Conor McGregor no UFC"},"content":{"rendered":"<figure id=\"attachment_20291\" aria-describedby=\"caption-attachment-20291\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-20291\" src=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2015\/12\/12314632_10153679625556276_8250843283502967312_o.jpg\" alt=\"Jos\u00e9 Aldo volta a pedir revanche com McGregor - Divulga\u00e7\u00e3o\" width=\"800\" height=\"552\" srcset=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2015\/12\/12314632_10153679625556276_8250843283502967312_o.jpg 800w, https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2015\/12\/12314632_10153679625556276_8250843283502967312_o-300x207.jpg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-20291\" class=\"wp-caption-text\"><em><strong>Jos\u00e9 Aldo volta a pedir revanche com McGregor &#8211; Divulga\u00e7\u00e3o<\/strong><\/em><\/figcaption><\/figure>\n<p>O ex campe\u00e3o peso leve do UFC, Jos\u00e9 Aldo voltou a fazer campanha para enfrentar o irland\u00eas Conor McGregor no UFC.<\/p>\n<p>Pedindo uma oportunidade, o lutador que vem insistindo por uma revanche contra McGregor, quer mostrar que desta vez o duelo vai ter outro resultado.<\/p>\n<p><em>&#8220;Estou esperando j\u00e1 essa revanche. Para mim isso j\u00e1 \u00e9 certo. N\u00e3o vejo como eles n\u00e3o darem. J\u00e1 fizeram pesquisa e sempre me colocaram na frente, at\u00e9 porque n\u00e3o teve luta. <\/em><\/p>\n<p><em>Todos querem me ver batendo nele, ent\u00e3o \u00e9 isso que eu vou fazer. E eu vou passar por cima dele isso \u00e9 fato. <\/em><\/p>\n<p><em>N\u00e3o vejo outro cen\u00e1rio na minha cabe\u00e7a al\u00e9m desse: Eu chegando l\u00e1, vencendo e pegando meu cintur\u00e3o de volta.&#8221;<\/em> disse o lutador em entrevista ao programa Esporte Espetacular, da Rede Globo de Televis\u00e3o.<\/p>\n<p>Apesar dos pedidos de Aldo, o brasileiro tem dois concorrentes para se tornar o pr\u00f3ximo a enfrentar o irland\u00eas: os americanos Frankie Edgar e Nate Diaz (\u00faltimo a lutar e que venceu Conor no UFC 196).<\/p>\n<p>Para isso, o atleta resolveu mudar sua postura e imitando o estilo de Conor, atrair a aten\u00e7\u00e3o do p\u00fablico para garantir a oportunidade.<\/p>\n<p><em>&#8220;Na verdade a gente vai ter que jogar o jogo que o McGregor jogou. A gente vai falar, vai trazer os holofotes da m\u00eddia pra cima. <\/em><\/p>\n<p><em>Para que o pessoal queira mais a luta do Aldo com McGregor do que a luta do Frank com o McGregor.&#8221;<\/em> declarou Aldo.<\/p>\n<p>Por\u00e9m os planos do irland\u00eas podem frustrar o desejo do ex campe\u00e3o.<\/p>\n<p>Nesta semana, o site americano MMA Fighting divulgou que uma suposta revanche de Conor com Nate Diaz estaria sendo negociada para a edi\u00e7\u00e3o 200 da organiza\u00e7\u00e3o, que acontece em julho deste ano.<\/p>\n<figure id=\"attachment_21075\" aria-describedby=\"caption-attachment-21075\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21075\" src=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2016\/03\/12829272_973061836062683_5788399497493898942_o.jpg\" alt=\"Revanche de McGregor com Diaz pode frustrar planos de Aldo - Divulga\u00e7\u00e3o\" width=\"800\" height=\"533\" srcset=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2016\/03\/12829272_973061836062683_5788399497493898942_o.jpg 800w, https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2016\/03\/12829272_973061836062683_5788399497493898942_o-300x200.jpg 300w, https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2016\/03\/12829272_973061836062683_5788399497493898942_o-768x512.jpg 768w, https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2016\/03\/12829272_973061836062683_5788399497493898942_o-120x80.jpg 120w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-21075\" class=\"wp-caption-text\"><em><strong>Revanche de McGregor com Diaz pode frustrar planos de Aldo &#8211; Divulga\u00e7\u00e3o<\/strong><\/em><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O ex campe\u00e3o peso leve do UFC, Jos\u00e9 Aldo voltou a fazer campanha para enfrentar o irland\u00eas Conor McGregor no UFC. Pedindo uma oportunidade, o <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/2016\/03\/21\/jose-aldo-volta-a-pedir-revanche-contra-conor-mcgregor-no-ufc\/\">leia mais<\/a><\/p>\n","protected":false},"author":33,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[614,83,12,1354,1368],"class_list":["post-21126","post","type-post","status-publish","format-standard","hentry","category-principal","tag-conor-mcgregor","tag-frankie-edgar","tag-jose-aldo","tag-nate-diaz","tag-ufc-200"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6rqUQ-5uK","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts\/21126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/comments?post=21126"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts\/21126\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/media?parent=21126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/categories?post=21126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/tags?post=21126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}