{"id":15383,"date":"2014-11-19T06:40:20","date_gmt":"2014-11-19T08:40:20","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/?p=15383"},"modified":"2014-11-19T06:40:20","modified_gmt":"2014-11-19T08:40:20","slug":"apos-grave-lesao-alan-nuguette-retorna-aos-treinos-e-mira-combate-em-abril-ou-maio","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/2014\/11\/19\/apos-grave-lesao-alan-nuguette-retorna-aos-treinos-e-mira-combate-em-abril-ou-maio\/","title":{"rendered":"Ap\u00f3s grave les\u00e3o, Alan Nuguette retorna aos treinos e mira combate em abril ou maio"},"content":{"rendered":"<figure id=\"attachment_15385\" aria-describedby=\"caption-attachment-15385\" style=\"width: 370px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2014\/11\/nuguete03_web_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15385\" alt=\"Lutador do UFC quer voltar a lutar em abril - Divulga\u00e7\u00e3o UFC\" src=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2014\/11\/nuguete03_web_.jpg\" width=\"370\" height=\"246\" \/><\/a><figcaption id=\"caption-attachment-15385\" class=\"wp-caption-text\"><strong><em>Lutador do UFC quer voltar a lutar em abril &#8211; Divulga\u00e7\u00e3o UFC<\/em><\/strong><\/figcaption><\/figure>\n<p>No final de setembro, pouco menos de um m\u00eas antes de enfrentar Beneil Dariush no UFC 179, no Rio de Janeiro, o peso-leve Alan Nuguette sofreu uma grave les\u00e3o na mand\u00edbula, ao receber uma joelhada no rosto durante os treinamentos, e teve de deixar o card. O lutador precisou passar por uma cirurgia para corre\u00e7\u00e3o da fratura uma semana ap\u00f3s o ocorrido e, na \u00faltima segunda-feira, dia 17 de novembro, retornou \u00e0 academia para dar in\u00edcio aos trabalhos de recondicionamento f\u00edsico, com muscula\u00e7\u00e3o e exerc\u00edcios aer\u00f3bios.<\/p>\n<p>O manauara, invicto na carreira com oito vit\u00f3rias, duas delas no Ultimate, fez seu \u00faltimo combate no UFC 169, em fevereiro deste ano, em New Jersey, contra o americano John Makdessi, e venceu por decis\u00e3o un\u00e2nime dos ju\u00edzes laterais. A experi\u00eancia de lutar nos EUA encantou Nuguette, que j\u00e1 projeta um pr\u00f3ximo duelo em solo norte-americano para abril ou maio de 2015, quando estiver totalmente recuperado da les\u00e3o. O atleta deve ser liberado para voltar normalmente aos treinos em janeiro.<\/p>\n<p>&#8220;Eu tenho muita vontade de voltar a lutar nos Estados Unidos. Eu fiz minha carreira toda aqui no Brasil e, apesar de gostar muito do calor do povo brasileiro, tenho muita vontade de voltar a lutar em um card l\u00e1 fora. A experi\u00eancia da minha \u00faltima luta foi incr\u00edvel e quero fazer meu nome l\u00e1 fora para crescer cada vez mais no UFC&#8221;, almeja Nuguette.<\/p>\n<p>A les\u00e3o que afastou Nuguette do oct\u00f3gono \u00e9 considerada muito rara, e at\u00e9 o final do ano ele s\u00f3 pode se alimentar com comidas pastosas. Mas o per\u00edodo de recupera\u00e7\u00e3o n\u00e3o est\u00e1 sendo s\u00f3 de dificuldade. O lutador foi pai pela primeira vez um pouco antes de se lesionar e tem aproveitado o tempo livre para se dedicar ao filho, o pequeno Alan Patrick, seu hom\u00f4nimo, de apenas dois meses e meio de vida.<\/p>\n<p>&#8220;Ele nasceu no meio da confus\u00e3o de luta, treinos e eu n\u00e3o podia me dedicar 100%. Agora estou sempre com ele, cuidando e babando. N\u00e3o \u00e9 uma experi\u00eancia t\u00e3o nova assim, j\u00e1 que eu cuidava dos filhos das minhas irm\u00e3s, minha fam\u00edlia sempre foi humilde e por isso tive que ajudar minha irm\u00e3, ent\u00e3o j\u00e1 tinha um pouco de no\u00e7\u00e3o. Mas quando \u00e9 o seu, \u00e9 outra hist\u00f3ria n\u00e9? Estou muito feliz e \u00e0s vezes at\u00e9 dividimos a comida, j\u00e1 que n\u00e3o posso comer nada duro, minha mulher brinca que est\u00e1 com dois beb\u00eas em casa (risos)&#8221;, diverte-se o lutador.<\/p>\n<p><b>Torcida por Melendez e elogios a Pettis na disputa de t\u00edtulo dos leves<\/b><\/p>\n<p>No dia 6 de dezembro, o UFC realiza sua edi\u00e7\u00e3o de n\u00famero 181 e um dos combates principais da noite \u00e9 a disputa de t\u00edtulo dos leves (at\u00e9 70,3kg), categoria de Nuguette, entre o atual campe\u00e3o Anthony Pettis e o desafiante Gilbert Melendez. Ambos foram os treinadores da 20\u00aa edi\u00e7\u00e3o do The Ultimate Fighter nos EUA e o manauara garante sua torcida pelo desafiante, mas n\u00e3o deixa de exaltar o jogo do campe\u00e3o.<\/p>\n<p>&#8220;O Melendez \u00e9 um cara muito forte e focado, mas o Pettis \u00e9 imprevis\u00edvel, lutar com um cara desses \u00e9 muito dif\u00edcil, ele foge do convencional e voc\u00ea n\u00e3o sabe o que esperar dele. Ent\u00e3o acredito que ele seja mais favorito, e a chance do Gilbert \u00e9 no ch\u00e3o. Vou torcer para o Melendez, mas acho que o Pettis leva com alguma maluquice daquela que ele tira da cartola, tem tudo para ser um grande combate&#8221;, confia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No final de setembro, pouco menos de um m\u00eas antes de enfrentar Beneil Dariush no UFC 179, no Rio de Janeiro, o peso-leve Alan Nuguette <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/2014\/11\/19\/apos-grave-lesao-alan-nuguette-retorna-aos-treinos-e-mira-combate-em-abril-ou-maio\/\">leia mais<\/a><\/p>\n","protected":false},"author":33,"featured_media":15385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-15383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-principal"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/files\/2014\/11\/nuguete03_web_.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6rqUQ-407","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts\/15383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/comments?post=15383"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/posts\/15383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/media\/15385"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/media?parent=15383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/categories?post=15383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/planeta-octogono\/wp-json\/wp\/v2\/tags?post=15383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}