{"id":5708,"date":"2017-06-14T21:34:23","date_gmt":"2017-06-15T00:34:23","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/?p=5708"},"modified":"2017-06-14T21:59:13","modified_gmt":"2017-06-15T00:59:13","slug":"apito-amigo-salva-sao-paulo-paulo-de-derrota-em-recife","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/2017\/06\/14\/apito-amigo-salva-sao-paulo-paulo-de-derrota-em-recife\/","title":{"rendered":"Apito amigo salva S\u00e3o Paulo de derrota em Recife&#8230;"},"content":{"rendered":"<figure id=\"attachment_5709\" aria-describedby=\"caption-attachment-5709\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2017\/06\/tricol.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5709\" src=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2017\/06\/tricol.jpg\" alt=\"\" width=\"800\" height=\"515\" srcset=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2017\/06\/tricol.jpg 800w, https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2017\/06\/tricol-300x193.jpg 300w, https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2017\/06\/tricol-768x494.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-5709\" class=\"wp-caption-text\">Foto: Rubens Chiri\/SPFC<\/figcaption><\/figure>\n<p>O \u00e1rbitro Heber Roberto Lopes deixou de dar duas penalidades m\u00e1ximas a favor do Sport, nesta quarta-feira \u00e0 noite na Ilha do Retiro, e quebrou o galho do S\u00e3o Paulo. Partida terminou sem gols n\u00e3o s\u00f3 pelo apito amigo. Os goleiros se destacaram tamb\u00e9m com grandes defesas, casos de Renan Ribeiro e Magr\u00e3o. Baixo n\u00edvel t\u00e9cnico chamou a aten\u00e7\u00e3o, com erros de passes dos dois lados. Resultado melhor para o Tricolor, que vinha de derrota para o Corinthians, no \u00faltimo domingo.<\/p>\n<p>O goleiro Renan Ribeiro salvou o S\u00e3o Paulo no primeiro tempo. O Sport chegou apenas uma vez e quase marcou. O ex-corintiano Andr\u00e9 bateu firme e seco e o goleiro fez &#8220;milagre&#8221;. E foi s\u00f3. S\u00f3 deu Tricolor. Com bom toque de bola, ligando defesa, meio-campo e ataque com rapidez, a grande oportunidades esteve nos p\u00e9s de Lucas Pratto. Hermano chegou livre, leve e solto na cara de Magr\u00e3o. Bastava apenas rolar para as redes. No entanto, escorregou na hora &#8220;h&#8221;. No duelo com Luxemburgo, Rog\u00e9rio Ceni mostrou-se ousado. Mandou o time para cima do advers\u00e1rio como se estivesse atuando no Morumbi. Lance duvidoso contra a equipe paulista. Tomaz empurrou advers\u00e1rio. Penalidade desprezada pelo \u00e1rbitro Heber Roberto Lopes.<\/p>\n<p>Na etapa final, logo de cara Andr\u00e9 desperdi\u00e7ou \u00f3tima chance de cabe\u00e7a. Na verdade, Luxa ter\u00e1 trabalho para consertar a equipe. Faltou realmente padr\u00e3o de jogo. Qual seria a t\u00e1tica do &#8220;Professor&#8221;? Aparentemente 4-4-2, se bem que v\u00e1rias vezes jogadores se amontoaram em um dos lados do campo, onde estava a bola. Estilo &#8220;pelada de final de semana&#8221;. J\u00e1 Ceni insistiu na forma\u00e7\u00e3o de tr\u00eas zagueiros, cinco no setor de meio-campo e dois no ataque.\u00a0 De novo, arriscou uma dupla de \u00e1rea com Pratto e Gilberto (saiu Wellington Nem).<\/p>\n<p>Atabalhoado, Sport amea\u00e7ou. Everton Felipe penetrou pela direita. O certo seria cruzar. Bateu para gol e Renan Ribeiro espalmou. Time da casa desceu com quatro e esbarrou em uma linha de sete defensores. Ou seja, ficou sempre em desvantagem num\u00e9rica. J\u00e1 nos acr\u00e9scimos, Gilberto testou forte, na pequena \u00e1rea, e Magr\u00e3o foi buscar. Andr\u00e9, por sua vez, levou um rapa de Wesley dentro da pequena \u00e1rea. P\u00eanalti claro. Heber Roberto Lopes ignorou e livrou a barra de Ceni.<\/p>\n<p>E assim caminha o apito amigo e a mediocridade&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O \u00e1rbitro Heber Roberto Lopes deixou de dar duas penalidades m\u00e1ximas a favor do Sport, nesta quarta-feira \u00e0 noite na Ilha do Retiro, e quebrou <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/2017\/06\/14\/apito-amigo-salva-sao-paulo-paulo-de-derrota-em-recife\/\">leia mais<\/a><\/p>\n","protected":false},"author":5,"featured_media":5709,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-5708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2017\/06\/tricol.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paxTb8-1u4","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts\/5708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/comments?post=5708"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts\/5708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/media\/5709"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/media?parent=5708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/categories?post=5708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/tags?post=5708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}