{"id":5430,"date":"2017-02-04T19:24:29","date_gmt":"2017-02-04T21:24:29","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/?p=5430"},"modified":"2017-02-04T19:33:02","modified_gmt":"2017-02-04T21:33:02","slug":"na-malandragem-de-jo-timao-faz-bonito-em-sorocaba","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/2017\/02\/04\/na-malandragem-de-jo-timao-faz-bonito-em-sorocaba\/","title":{"rendered":"Na malandragem de J\u00f4, Tim\u00e3o faz bonito em Sorocaba&#8230;"},"content":{"rendered":"<figure id=\"attachment_5431\" aria-describedby=\"caption-attachment-5431\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2017\/02\/jo-lang.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-5431\" src=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2017\/02\/jo-lang-1024x681.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2017\/02\/jo-lang-1024x681.jpg 1024w, https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2017\/02\/jo-lang-300x200.jpg 300w, https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2017\/02\/jo-lang-768x511.jpg 768w, https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2017\/02\/jo-lang-120x80.jpg 120w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><figcaption id=\"caption-attachment-5431\" class=\"wp-caption-text\">Foto: Fernando Dantas\/Gazeta Press<\/figcaption><\/figure>\n<p>O Corinthians estreou com o p\u00e9 direito no Paulist\u00e3o-2017. Venceu o S\u00e3o Bento, em Sorocaba, por 1 a 0, nesse s\u00e1bado \u00e0 tarde, e na base da malandragem de J\u00f4. Partida estava equilibrada, gramado molhada\u00e7o, quando aos 9 minutos do segundo tempo, o camisa 7 arrancou com fome de gol. Vinha sendo puxado pelo ombro desde de fora da \u00e1rea. Quando viu que a arbitragem estava demorando para marcar falta, deixou o corpo para o choque de canela com canela. Valeu a mal\u00edcia, a experi\u00eancia internacional do atacante. Ele mesmo cobrou, fez o primeiro gol no retorno ao Tim\u00e3o e garantiu tr\u00eas pontinhos diante de um advers\u00e1rio chato (ano passado nem perdeu em casa pelo Paulista).<\/p>\n<p>O desentrosamento talvez seja o principal problema do t\u00e9cnico Fabio Carille nesse in\u00edcio de temporada. J\u00f4 mesmo reclamou no intervalo. Afinal, ganhou todas as bolas pelo alto (na famosa &#8220;casquinha&#8221;, uma esp\u00e9cie de desvio deixando companheiros livres na frente do gol) e ningu\u00e9m se aproveitou dessa op\u00e7\u00e3o. Rodriguinho estava totalmente anulado pela zaga aoposta. Faltou Felipe Bastos e mesmo Gabriel encostarem mais para ajudar o companheiro. Outro detalhe negativo: Marlone pela esquerda e Giovanni Augusto pela direita imp\u00f5em respeito, por\u00e9m, n\u00e3o t\u00eam velocidade, rapidez para surpreender pelas laterais.<\/p>\n<p>Elogios para o zagueiro Pablo (n\u00e3o errou uma nas bolas altas) e para Mois\u00e9s (forte, chega chuto e apoia bem). O goleiro C\u00e1ssio quase se complicou em cobran\u00e7a de falta (deveria ter espalmado e quis agarrar) e Fagner sempre no mesmo ritmo, ora ofensivo, ora defensivo. Zaga, desta vez, n\u00e3o comprometeu.<\/p>\n<p>\u00d3timo resultado para uma equipe em forma\u00e7\u00e3o em estreia fora de casa.<\/p>\n<p>E tenho dito!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Corinthians estreou com o p\u00e9 direito no Paulist\u00e3o-2017. Venceu o S\u00e3o Bento, em Sorocaba, por 1 a 0, nesse s\u00e1bado \u00e0 tarde, e na <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/2017\/02\/04\/na-malandragem-de-jo-timao-faz-bonito-em-sorocaba\/\">leia mais<\/a><\/p>\n","protected":false},"author":5,"featured_media":5431,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-5430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2017\/02\/jo-lang.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paxTb8-1pA","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts\/5430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/comments?post=5430"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts\/5430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/media\/5431"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/media?parent=5430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/categories?post=5430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/tags?post=5430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}