{"id":2571,"date":"2014-07-17T09:35:13","date_gmt":"2014-07-17T12:35:13","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/?p=2571"},"modified":"2014-07-17T14:50:58","modified_gmt":"2014-07-17T17:50:58","slug":"a-ficha-caiu-alemanha-leva-14-anos-para-ser-tetra-na-bacia-das-almas","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/2014\/07\/17\/a-ficha-caiu-alemanha-leva-14-anos-para-ser-tetra-na-bacia-das-almas\/","title":{"rendered":"Cai a ficha: Alemanha leva 14 anos para ser tetra na bacia das almas"},"content":{"rendered":"<p><figure id=\"attachment_1890\" aria-describedby=\"caption-attachment-1890\" style=\"width: 595px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2013\/08\/chico1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2013\/08\/chico1.jpg\" alt=\"Fernando Dantas\/Gazeta Press\" width=\"595\" height=\"396\" class=\"size-full wp-image-1890\" \/><\/a><figcaption id=\"caption-attachment-1890\" class=\"wp-caption-text\">Fernando Dantas\/Gazeta Press<\/figcaption><\/figure>Passada a Copa 2014, caiu a ficha. Os alem\u00e3es levaram 14 anos para desenvolver um trabalho de base e levantar um tetra mundial (\u00faltimo aconteceu em 1990). Aqui entre n\u00f3s, muito esfor\u00e7o para pouco resultado.Sem contar que o futebol dos chucrutes n\u00e3o \u00e9 grande coisa. Afinal, argentinos perderam dois gols feitos durante a final\u00edssima. Germ\u00e2nicos marcaram na bacia das almas da prorroga\u00e7\u00e3o<\/p>\n<p>Brasil perdeu de 7 a 1 dos caras, \u00e9 verdade. Mas atuou aberto, sem marca\u00e7\u00e3o no meio-campo. Nos jogos anteriores, contra advers\u00e1rios fechados, os atuais campe\u00f5es encontraram grandes dificuldades. Portugal cometeu o mesmo erro e acabou levando goleada. Gana, Arg\u00e9lia, Estados Unidos e Fran\u00e7a deram sufoco neles. Hermanos idem.<\/p>\n<p>A conquista est\u00e1 sendo supervalorizada. Principalmente pelo pessoal que deseja ver o circo pegar fogo aqui na bola brasileira. Os nomes de Jos\u00e9 Maria Marin e Marco Polo Del Nero transformaram-se em sin\u00f4nimos de &#8220;coisa retrograda&#8221;. Felip\u00e3o e Parreira, mitos at\u00e9 ent\u00e3o s\u00e3o tratados como vil\u00f5es. Ricardo Teixeira e Tel\u00ea Santana foram melhores?. Zico e Pel\u00e9 chegaram a ministros dos Esportes. E o que mudou? Absolutamente nada.<\/p>\n<p>Todas federa\u00e7\u00f5es e clubes est\u00e3o na ro\u00e7a. Federa\u00e7\u00f5es t\u00eam dinheiro, mas n\u00e3o sabem onde gastar. Da\u00ed uma prov\u00e1vel corrup\u00e7\u00e3o vira tenta\u00e7\u00e3o. Os clubes est\u00e3o duros, por\u00e9m, s\u00e3o obrigados a montar grandes elencos para serem campe\u00f5es. Ningu\u00e9m se salva. <\/p>\n<p>Um clube faz dois bons campeonatos e cai para Segundona no terceiro ano. N\u00e3o pode ser m\u00e1 administra\u00e7\u00e3o somente. Todos batem com a cara no muro do ainda quase amadorismo e da maldita Lei Pel\u00e9: jogadores e empres\u00e1rios est\u00e3o ricos e os clubes vendem o almo\u00e7o para pagar a janta.<\/p>\n<p>Brasileir\u00e3o, por exemplo, cada time tem 39 jogos e 20 clubes. S\u00e3o meses de disputa. Apenas 15 jogadores n\u00e3o seguram a onda. Um elenco competitivo necessita ter dois bons atletas para cada posi\u00e7\u00e3o. Com sal\u00e1rios l\u00e1 em cima.<\/p>\n<p>O qu\u00ea fazer?<\/p>\n<p>Est\u00e1 na hora sim de colocar as chuteiras no ch\u00e3o e parar de imitar os europeus. Campeonatos mata-mata sempre foram mais atraentes e baratos. D\u00e1 para fazer estaduais, um bom nacional, uma \u00f3tima Copa do Brasil, al\u00e9m de torneios como  Rio-S\u00e3o Paulo, S\u00e3o Paulo-Nordeste, Rio-Minas e assim por diante e ter um lucro muito maior. O ibope baixo das TVs abertas e a pouca procura das fechadas que o digam.<\/p>\n<p>Antes de mais nada respeitemos a cultura e os costumes do nosso pais. N\u00e3o somos alem\u00e3es, ingleses, franceses, holandeses  ou  coisa que o valha. Somos melhores do que eles com a bola nos p\u00e9s. Imit\u00e1-los para qu\u00ea?<\/p>\n<p>E tenho dito!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Passada a Copa 2014, caiu a ficha. Os alem\u00e3es levaram 14 anos para desenvolver um trabalho de base e levantar um tetra mundial (\u00faltimo aconteceu <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/2014\/07\/17\/a-ficha-caiu-alemanha-leva-14-anos-para-ser-tetra-na-bacia-das-almas\/\">leia mais<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-2571","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paxTb8-Ft","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts\/2571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/comments?post=2571"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts\/2571\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/media?parent=2571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/categories?post=2571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/tags?post=2571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}