{"id":2540,"date":"2014-07-11T14:01:54","date_gmt":"2014-07-11T17:01:54","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/?p=2540"},"modified":"2014-07-11T17:56:12","modified_gmt":"2014-07-11T20:56:12","slug":"futebol-brasileiro-chegara-a-rebeliao-dificilmente-a-revolucao-total","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/2014\/07\/11\/futebol-brasileiro-chegara-a-rebeliao-dificilmente-a-revolucao-total\/","title":{"rendered":"Futebol brasileiro chegar\u00e1 \u00e0 rebeli\u00e3o, dificilmente \u00e0 revolu\u00e7\u00e3o total"},"content":{"rendered":"<p><figure id=\"attachment_2517\" aria-describedby=\"caption-attachment-2517\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2014\/07\/fred_640_sb1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2014\/07\/fred_640_sb1.jpg\" alt=\"Sergio Barzaghi\/Gazeta Press\" width=\"620\" height=\"346\" class=\"size-full wp-image-2517\" \/><\/a><figcaption id=\"caption-attachment-2517\" class=\"wp-caption-text\">Sergio Barzaghi\/Gazeta Press<\/figcaption><\/figure>Depois do vexame diante da Alemanha (7 a 1) muita gente questiona se n\u00e3o est\u00e1 na hora de revolucionar o futebol brasileiro. Mudar tudo. Jogar uma bomba em cima e come\u00e7ar do zero. A id\u00e9ia, o conceito, exige uma explica\u00e7\u00e3o mais detalhada. A palavra &#8220;revolu\u00e7\u00e3o&#8221; significa &#8220;reviravolta, virar uma situa\u00e7\u00e3o de pernas para o ar&#8221;. Sinceramente, quem no Brasil tem coragem para mexer com o caudilhos da bola? Andr\u00e9s Sanchez, ex-presidente do Corinthians, at\u00e9 tentou. E nada conseguiu. Tirou o time de campo para n\u00e3o levar uma lavada humilhante na \u00faltima elei\u00e7\u00e3o da CBF.<\/p>\n<p>A estrutura da entidade m\u00e1xima da bola nacional s\u00e3o profundas e s\u00f3lidas. Permitem a corrup\u00e7\u00e3o, a explora\u00e7\u00e3o de jogadores por empres\u00e1rios e tratam o ser humano como mercadoria. Todos possuem um valor de uso, de troca, prazo de validade. Criaram um mercado com leis, normas e outras ferramentas convenientes para a &#8220;m\u00e1quina de fazer dinheiro&#8221; continuar funcionando, custe o que custar.<\/p>\n<p>Em nosso Pa\u00eds, pior que misturar bola com pol\u00edtica, \u00e9 a pr\u00f3pria pol\u00edtica da bola. Clubes t\u00eam um jeito padronizado de se relacionarem com torcedores, empres\u00e1rios e jogadores. Os pol\u00edticos de carreira d\u00e3o uma bicada aqui e ali. E s\u00f3. Dirigentes sim tiram grandes proveitos, com uma esp\u00e9cie de &#8220;micro poder&#8221; dentro de um &#8220;macro poder&#8221; (para lembrar de Michel Foucault). Um pode ser a c\u00f3pia do outro, mas s\u00e3o diferentes. T\u00eam outros objetivos. Seria uma &#8220;m\u00e1quina menor&#8221; dentro de uma &#8220;m\u00e1quina maior&#8221;.<\/p>\n<p>Por isso que, no m\u00e1ximo, poderemos assistir nos pr\u00f3ximos anos uma rebeli\u00e3o. Ou seja, alguns pontos de indigna\u00e7\u00e3o, de revolta, poder\u00e3o ser reivindicados e atendidos. Mudan\u00e7a de hor\u00e1rios de jogos de TV ou altera\u00e7\u00f5es no calend\u00e1rio de jogos, por exemplo. A cria\u00e7\u00e3o de departamento de Psicol\u00f3gia pode ser outra alternativa. Na infraestrutura, por\u00e9m, ningu\u00e9m bota a m\u00e3o. Ou seja, as rela\u00e7\u00f5es clubes, empres\u00e1rios, jogadores, CBF, Fifa ser\u00e3o mantidas em termos globalizados. Fazem parte de um sistema maior, o &#8220;Livre Mercado&#8221; planet\u00e1rio, ou como diria o finado Pl\u00ednio Salgado, &#8220;o capitalismo selvagem&#8221;.<\/p>\n<p>Uma rebeli\u00e3o, meus amigos, j\u00e1 seria muito bem vinda. Tor\u00e7o por ela. Mas j\u00e1 desisti de uma revolu\u00e7\u00e3o.<\/p>\n<p>E tenho dito!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois do vexame diante da Alemanha (7 a 1) muita gente questiona se n\u00e3o est\u00e1 na hora de revolucionar o futebol brasileiro. Mudar tudo. Jogar <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/2014\/07\/11\/futebol-brasileiro-chegara-a-rebeliao-dificilmente-a-revolucao-total\/\">leia mais<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-2540","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paxTb8-EY","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts\/2540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/comments?post=2540"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts\/2540\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/media?parent=2540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/categories?post=2540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/tags?post=2540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}