{"id":2422,"date":"2014-06-17T17:53:13","date_gmt":"2014-06-17T20:53:13","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/?p=2422"},"modified":"2014-06-17T21:15:09","modified_gmt":"2014-06-18T00:15:09","slug":"selecao-de-felipao-tropeca-na-ruindade-e-so-empata-com-mexico","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/2014\/06\/17\/selecao-de-felipao-tropeca-na-ruindade-e-so-empata-com-mexico\/","title":{"rendered":"Sele\u00e7\u00e3o de Felip\u00e3o trope\u00e7a na ruindade e s\u00f3 empata com M\u00e9xico"},"content":{"rendered":"<figure id=\"attachment_2428\" aria-describedby=\"caption-attachment-2428\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2014\/06\/blog_lang6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2428\" alt=\"Wagner Carmo\/Gazeta Press\" src=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2014\/06\/blog_lang6.jpg\" width=\"640\" height=\"350\" \/><\/a><figcaption id=\"caption-attachment-2428\" class=\"wp-caption-text\">Wagner Carmo\/Gazeta Press<\/figcaption><\/figure>\n<p>Uma sele\u00e7\u00e3o brasileira tensa, sem jogadas ensaiadas, com medo de ir para frente e resolver a partida. Da\u00ed o empate sem gols diante do fraco M\u00e9xico. Quando o time teve um pouco de lucidez, o goleiro Ochoa fez \u00f3timas defesas e salvou a p\u00e1tria. Classifica\u00e7\u00e3o, dessa forma, fica amea\u00e7ada e vai depender de fracassos de Cro\u00e1cia, Camar\u00f5es e dos pr\u00f3prios mexicanos. Resultado decepcionou e frustou a todos.<\/p>\n<p>N\u00e3o foi no primeiro tempo que a torcida brasileira pode ver um futebol d\u00edgno de uma sele\u00e7\u00e3o pentacampe\u00e3 do mundo. A bola &#8220;queimou&#8221; de p\u00e9 em p\u00e9. Time estava mal posicionado. Entre a defesa, o meio-campo e o ataque parecia existir &#8220;valetas&#8221;, isto \u00e9, um barreira invis\u00edvel, evitando uma troca de passes mais eficaz. Da\u00ed se explica o motivo de apenas duas conclus\u00f5es contra o gol advers\u00e1rio. Uma de cabe\u00e7a, com Neymar e outra com Paulinho, cara a cara com o goleiro.<\/p>\n<p>Mexicanos, por sua vez, dividiram o est\u00e1dio com a torcida nacional, fora de campo. No gramado, ficou claro estarem esperando um erro brasileiro para definir uma situa\u00e7\u00e3o de gol, o que n\u00e3o aconteceu, apesar de o time do t\u00e9cnico Felip\u00e3o ter perdido quase todos os rebotes, ali\u00e1s, como vem ocorrendo ultimamente.<\/p>\n<p>Na etapa final, saiu Ramires e veio Bernard. De cara, o ex-atleticano cruzou e zaga chegou antes de Neymar. No entanto, o M\u00e9xico se agigantou. Marcou com precis\u00e3o a fraca sa\u00edda de bola da Canarinho e come\u00e7ou a dar &#8220;ol\u00e9&#8221;, por incr\u00edvel que pare\u00e7a. Equipe nacional irreconhec\u00edvel. De falta, Neymar amea\u00e7ou e isso aos 18 mim. Fred deixou o gramado vaiado e veio J\u00f4. De novo Neymar bateu e o goleiro pegou. Ochoa salvou os mexicanos de novo e testada de Tiago Silva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma sele\u00e7\u00e3o brasileira tensa, sem jogadas ensaiadas, com medo de ir para frente e resolver a partida. Da\u00ed o empate sem gols diante do fraco <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/chicolang\/2014\/06\/17\/selecao-de-felipao-tropeca-na-ruindade-e-so-empata-com-mexico\/\">leia mais<\/a><\/p>\n","protected":false},"author":5,"featured_media":2428,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-2422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/files\/2014\/06\/blog_lang6.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paxTb8-D4","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts\/2422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/comments?post=2422"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/posts\/2422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/media\/2428"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/media?parent=2422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/categories?post=2422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/chicolang\/wp-json\/wp\/v2\/tags?post=2422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}