{"id":4969,"date":"2015-08-20T00:13:08","date_gmt":"2015-08-20T03:13:08","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/?p=4969"},"modified":"2015-08-20T00:18:23","modified_gmt":"2015-08-20T03:18:23","slug":"deu-santos-com-meritos","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/2015\/08\/20\/deu-santos-com-meritos\/","title":{"rendered":"Deu Santos, com m\u00e9ritos"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2015\/08\/peixe.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4975\" data-permalink=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/2015\/08\/20\/deu-santos-com-meritos\/peixe\/\" data-orig-file=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2015\/08\/peixe.jpg\" data-orig-size=\"2000,1233\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"peixe\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2015\/08\/peixe-300x185.jpg\" data-large-file=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2015\/08\/peixe-1024x631.jpg\" class=\"aligncenter size-large wp-image-4975\" src=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2015\/08\/peixe-1024x631.jpg\" alt=\"peixe\" width=\"640\" height=\"394\" srcset=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2015\/08\/peixe-1024x631.jpg 1024w, https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2015\/08\/peixe-300x185.jpg 300w, https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2015\/08\/peixe.jpg 2000w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>Ao apito inicial do juiz, o Santos armou sua barraca na praia do Tim\u00e3o, acendeu a fogueira e ficou ali cozinhando o primeiro gol, que s\u00f3 alcan\u00e7ou o ponto certo aos 31 minutos, com aquele passe magistral de Lucas Lima para Gabigol finalizar por tr\u00e1s da zaga.<\/p>\n<p>Antes disso e depois, s\u00f3 deu Santos ao longo de todo o primeiro tempo. E o placar s\u00f3 n\u00e3o se desdobrou por conta das boas defesas de C\u00e1ssio e das interven\u00e7\u00f5es providenciais dos defensores alvinegros. E tamb\u00e9m porque o artilheiro do time e do campeonato, Ricardo Oliveira, n\u00e3o estava inspirado nos momentos de finaliza\u00e7\u00e3o. Perdeu duas chances de ouro, uma na etapa inicial, outra na final, cara a cara com C\u00e1ssio.<\/p>\n<p>A quem n\u00e3o faltava inspira\u00e7\u00e3o era Lucas Lima, como de h\u00e1bito, que continuou segundo tempo adentro criando jogadas para seus companheiros e produzindo lances de encantar quem gosta desse jogo da bola.<\/p>\n<p>\u00c9 bem verdade que, no per\u00edodo final, o Corinthians levantou um pouco a crista, mas j\u00e1 com Love no lugar de Luciano, que havia se machucado. Quer dizer: as poucas oportunidades criadas pelo Corinthians foram mais as daquela bola repicando na \u00e1rea santista.<\/p>\n<p>E, quando, finalmente, o Tim\u00e3o conseguiu se firmar no campo oposto, veio o\u00a0 contragolpe fatal. N\u00e3o fruto de um daqueles bal\u00f5es esticados aleatoriamente l\u00e1 de tr\u00e1s, n\u00e3o. Foi com a bola trabalhada pela direita, em exata trama entre Victor Ferraz, Renato, Lucas Lima e Marquinhos Gabriel, que foi decisivo na enfiada esperta de Lucas Lima: 2 a 0, placar que, se deixa o Peixe mais tranquilo para o jogo em Itaquera, n\u00e3o tira as esperan\u00e7as do Corinthians, que ainda tem bala pra virar esse jogo dobrado.<\/p>\n<p>Basta ousar mais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao apito inicial do juiz, o Santos armou sua barraca na praia do Tim\u00e3o, acendeu a fogueira e ficou ali cozinhando o primeiro gol, que <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/2015\/08\/20\/deu-santos-com-meritos\/\">leia mais<\/a><\/p>\n","protected":false},"author":46,"featured_media":4975,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"jetpack_featured_media_url":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2015\/08\/peixe.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pekB7q-1i9","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/posts\/4969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/comments?post=4969"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/posts\/4969\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/media\/4975"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/media?parent=4969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/categories?post=4969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/tags?post=4969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}