{"id":383,"date":"2014-07-29T18:29:43","date_gmt":"2014-07-29T21:29:43","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/?p=383"},"modified":"2014-07-29T18:36:04","modified_gmt":"2014-07-29T21:36:04","slug":"milonga-e-tarantella-no-centenario-verde","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/2014\/07\/29\/milonga-e-tarantella-no-centenario-verde\/","title":{"rendered":"Milonga e tarantella no centen\u00e1rio verde"},"content":{"rendered":"<figure id=\"attachment_389\" aria-describedby=\"caption-attachment-389\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2014\/07\/gareca2.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"389\" data-permalink=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/2014\/07\/29\/milonga-e-tarantella-no-centenario-verde\/gareca2\/\" data-orig-file=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2014\/07\/gareca2.jpg\" data-orig-size=\"640,426\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Fernando Dantas\/Gazeta Press\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Fernando Dantas\/Gazeta Press&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2014\/07\/gareca2.jpg\" data-large-file=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2014\/07\/gareca2.jpg\" class=\"size-full wp-image-389\" alt=\"Fernando Dantas\/Gazeta Press\" src=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2014\/07\/gareca2.jpg\" width=\"640\" height=\"426\" \/><\/a><figcaption id=\"caption-attachment-389\" class=\"wp-caption-text\">Fernando Dantas\/Gazeta Press<\/figcaption><\/figure>\n<p>Neste ano de seu centen\u00e1rio, o Palmeiras, em vez de dan\u00e7ar a<em> tarantella<\/em> de suas ilustres origens, canta um tango, at\u00e9 agora, lacrimoso, \u00e0 espera do momento da mudan\u00e7a do ritmo da guitarra para a alegre e p\u00edcara milonga argentina.<\/p>\n<p>Tanto, que o t\u00e9cnico Gareca j\u00e1 pensa em lan\u00e7ar na noite desta quarta-feira, contra a Fiorentina, pela Copa Euroamericana (mais uma neste calend\u00e1rio sem f\u00f4lego do futebol brasileiro), o seu compatriota Allione, que desembarcou ontem em S\u00e3o Paulo sem ter a m\u00ednima ideia de onde fica a Pra\u00e7a da S\u00e9. Mais um dentre tantos argentinos recentemente contratados pelo Palmeiras. E, pelo que dizem, v\u00eam mais por a\u00ed.<\/p>\n<p>Nada contra a importa\u00e7\u00e3o de t\u00e9cnicos e jogadores estrangeiros, sobretudo argentinos e uruguaios, duas escolas respeit\u00e1veis no mundo todo, a vida toda.<\/p>\n<p>Ali\u00e1s, vale lembrar que t\u00e9cnicos argentinos e uruguaios, como Conrado Ross, Jim Lopes, Ondino Vieira, Filpo Nu\u00f1es e tantos outros que aqui aportaram d\u00e9cadas atr\u00e1s muito contribu\u00edram para o avan\u00e7o do nosso futebol, sempre carente de boas e novas experi\u00eancias t\u00e1ticas.<\/p>\n<p>Isso, sem falar em dois h\u00fangaros providenciais: Dori Kruschner, que, na d\u00e9cada de 30, implantou no Flamengo o WM, revolucionando o sistema t\u00e1tico (o cl\u00e1ssico 2-3-5) adotado no Brasil, e Bella Gutman, que, ao assumir o S\u00e3o Paulo, em 57, imprimiu a objetividade que nos faltava, o mesmo conceito imposto por Feola, que era supervisor do Tricolor \u00e0 \u00e9poca de Gutman, na conquista do primeiro Mundial pelo Brasil na Su\u00e9cia.<\/p>\n<p>Muito menos condeno a importa\u00e7\u00e3o de jogadores argentinos, que v\u00eam da segunda maior usina de craques do mundo (a primeira ainda \u00e9 o Brasil, sobretudo pelo tamanho da nossa popula\u00e7\u00e3o). Sucede que, no passado, os argentinos, uruguaios, paraguaios, chilenos, peruanos e colombianos contratados pelos brasileiros eram craques consumados, de Sele\u00e7\u00e3o, mesmo que no limiar do fim de carreira. Agora, com o filtro de ouro europeu, resta-nos trazer jogadores de n\u00edvel, no m\u00ednimo, duvidoso.<\/p>\n<p>O que me incomoda um pouco \u00e9 esse vi\u00e9s de compadrio que marca n\u00e3o s\u00f3 a presen\u00e7a de Gareca no Palmeiras, mas, tamb\u00e9m dos t\u00e9cnicos brasileiros em geral. Essa coisa de se cercar de jogadores com os quais j\u00e1 tenham trabalhado neste ou naquele clube.<\/p>\n<p>Fosse eu t\u00e9cnico de futebol, ganhando, sei l\u00e1, 300, 500 mil, um milh\u00e3o por m\u00eas, destinaria metade dessa grana para montar uma rede de olheiros mundo afora que me enviariam relat\u00f3rios, v\u00eddeos, o diabo a quatro, sobre tais e quais jogadores poderiam ser utilizados de acordo com minhas necessidades. O mesmo se aplica aos clubes que torram fortunas indo na conversa deste ou daquele na hora de contratar jogadores, e, que, por inc\u00faria, deixaram nas m\u00e3os dos empres\u00e1rios essa tarefa.<\/p>\n<p>Nenhum esquema garante vit\u00f3rias em futebol, esse jogo t\u00e3o caprichoso. Mas, quanto menos margem de erro voc\u00ea tiver, mais chances de \u00eaxito ter\u00e1.<\/p>\n<p>Do jeito que a coisa anda, s\u00f3 resta torcer pra que d\u00ea certo, e o Palmeiras consiga decolar com essa leva de argentinos, ao som de uma milonga divertida, alternada com a mal\u00edcia da <em>tarantella <\/em>dos velhos tempos do Palestra centen\u00e1rio.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste ano de seu centen\u00e1rio, o Palmeiras, em vez de dan\u00e7ar a tarantella de suas ilustres origens, canta um tango, at\u00e9 agora, lacrimoso, \u00e0 espera <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/2014\/07\/29\/milonga-e-tarantella-no-centenario-verde\/\">leia mais<\/a><\/p>\n","protected":false},"author":46,"featured_media":389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"jetpack_featured_media_url":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2014\/07\/gareca2.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pekB7q-6b","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/posts\/383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/comments?post=383"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/posts\/383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/media\/389"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/media?parent=383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/categories?post=383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/tags?post=383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}