{"id":356,"date":"2014-07-28T13:28:38","date_gmt":"2014-07-28T16:28:38","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/?p=356"},"modified":"2014-07-28T18:52:18","modified_gmt":"2014-07-28T21:52:18","slug":"a-faixa-contra-a-favor","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/2014\/07\/28\/a-faixa-contra-a-favor\/","title":{"rendered":"A faixa contra, a favor"},"content":{"rendered":"<figure id=\"attachment_364\" aria-describedby=\"caption-attachment-364\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2014\/07\/helena24.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"364\" data-permalink=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/2014\/07\/28\/a-faixa-contra-a-favor\/helena2-5\/\" data-orig-file=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2014\/07\/helena24.jpg\" data-orig-size=\"640,420\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"SSPress\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;SSPress&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2014\/07\/helena24.jpg\" data-large-file=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2014\/07\/helena24.jpg\" class=\"size-full wp-image-364\" alt=\"SSPress\" src=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2014\/07\/helena24.jpg\" width=\"640\" height=\"420\" \/><\/a><figcaption id=\"caption-attachment-364\" class=\"wp-caption-text\">SSPress<\/figcaption><\/figure>\n<p>A faixa exibida pelos jogadores do Botafogo antes do in\u00edcio do cl\u00e1ssico com o Flamengo, na reestreia de Luxemburgo na G\u00e1vea, cobrando sal\u00e1rios atrasados pelo clube, d\u00e1 o que pensar. Ser\u00e1 que foi um gesto justo e espont\u00e2neo do elenco alvinegro, ou teve no m\u00ednimo, o benepl\u00e1cito da diretoria?<\/p>\n<p>Explico: dois, tr\u00eas dias antes, o presidente do Botafogo participou, juntamente com mais onze de seus pares, da famosa reuni\u00e3o com a presidente Dilma, pedindo prolongamento de prazo para pagar aquela montanha de dinheiro que os clubes brasileiros devem ao er\u00e1rio p\u00fablico (leia-se nosso pobre dinheirinho).\u00a0 E at\u00e9 chegou a amea\u00e7ar de retirar seu time de campo, por falta de recursos para chegar ao fim do ano.<\/p>\n<p>O argumento dos cartolas \u00e9 a de que essa d\u00edvida tem a idade de Matusal\u00e9m. Fruto de m\u00e1 gest\u00e3o de seus antecessores. \u00c9 verdade, embora os atuais presidentes continuem cometendo os mesmos disparates administrativos de sempre, com as exce\u00e7\u00f5es de praxe, claro. (A manifesta\u00e7\u00e3o dos jogadores do Glorioso, nesse caso, serviria como press\u00e3o para Dilma e seus auxiliares justificarem a tal prorroga\u00e7\u00e3o pedida pelos clubes).<\/p>\n<p>Mas, ent\u00e3o, por que n\u00e3o se cobra dos antigos respons\u00e1veis por tantas irresponsabilidades? Basta fazer uma auditoria nos, digamos, vinte \u00faltimos anos de vida das entidades esportivas, separando o joio do trigo. E aqueles que cometeram os deslizes sejam devidamente responsabilizados, n\u00e3o apenas pelo governo, mas, sobretudo, pelos pr\u00f3prios clubes que eles levaram \u00e0 beira da fal\u00eancia?<\/p>\n<p>Pra tanto, n\u00e3o \u00e9 necess\u00e1rio Lei de Responsabilidade, como a que tramita no Congresso, ou medidas provis\u00f3rias. Basta a justi\u00e7a comum, a quem recorrem todos os que se sintam lesados por outrem.<\/p>\n<p>O que essa turma quer mesmo \u00e9 manter em campo o velho jogo do empurra. E quem paga o pato, no fim das contas, somos n\u00f3s, os contribuintes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A faixa exibida pelos jogadores do Botafogo antes do in\u00edcio do cl\u00e1ssico com o Flamengo, na reestreia de Luxemburgo na G\u00e1vea, cobrando sal\u00e1rios atrasados pelo <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/2014\/07\/28\/a-faixa-contra-a-favor\/\">leia mais<\/a><\/p>\n","protected":false},"author":46,"featured_media":364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"jetpack_featured_media_url":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2014\/07\/helena24.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pekB7q-5K","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/posts\/356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/comments?post=356"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/posts\/356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/media\/364"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/media?parent=356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/categories?post=356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/tags?post=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}