{"id":12293,"date":"2021-01-06T23:51:57","date_gmt":"2021-01-07T02:51:57","guid":{"rendered":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/?p=12293"},"modified":"2021-01-06T23:59:20","modified_gmt":"2021-01-07T02:59:20","slug":"tricolor-agradeca-aos-ceus","status":"publish","type":"post","link":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/2021\/01\/06\/tricolor-agradeca-aos-ceus\/","title":{"rendered":"Tricolor: agrade\u00e7a aos c\u00e9us"},"content":{"rendered":"<figure id=\"attachment_12295\" aria-describedby=\"caption-attachment-12295\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2021\/01\/5909_crop_galeria.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"12295\" data-permalink=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/2021\/01\/06\/tricolor-agradeca-aos-ceus\/5909_crop_galeria\/\" data-orig-file=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2021\/01\/5909_crop_galeria.jpg\" data-orig-size=\"800,515\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"5909_crop_galeria\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Foto: Divulga\u00e7\u00e3o\/Rubens Chiri&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2021\/01\/5909_crop_galeria-300x193.jpg\" data-large-file=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2021\/01\/5909_crop_galeria.jpg\" class=\"size-full wp-image-12295\" src=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2021\/01\/5909_crop_galeria.jpg\" alt=\"\" width=\"800\" height=\"515\" srcset=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2021\/01\/5909_crop_galeria.jpg 800w, https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2021\/01\/5909_crop_galeria-300x193.jpg 300w, https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2021\/01\/5909_crop_galeria-768x494.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-12295\" class=\"wp-caption-text\">Foto: Divulga\u00e7\u00e3o\/Rubens Chiri<\/figcaption><\/figure>\n<p>Bem que o S\u00e3o Paulo deveria acender um milh\u00e3o de velas a seu padroeiro e demais santos e orix\u00e1s (como costumava dizer meu saudoso e querido amigo Ciro Monteiro, pra quem \u00e9 de b\u00ean\u00e7\u00e3o, b\u00ean\u00e7\u00e3o; pra quem \u00e9 de sarav\u00e1, sarav\u00e1!).<\/p>\n<p>N\u00e3o s\u00f3 porque escapou de um vexame hist\u00f3rico diante do Red Bull, em Bragan\u00e7a, ao perder por apenas 4 a 2, quando o placar das chances perdidas elevaria esse resultado a uns 8 ou 9 a 2, sem exagero algum. Mas, sobretudo, porque o Flamengo, seu mais perigoso perseguidor no Brasileir\u00e3o, acabou perdendo, de virada, para o Flu, no cl\u00e1ssico do Maracan\u00e3, por 2 a 1.<\/p>\n<p>E, se o Tricolor paulista levou um baile do RB, sem revelar em nenhum momento qualquer poder de rea\u00e7\u00e3o, o Fla teve o jogo aos seus p\u00e9s a maior parte do tempo, sem conseguir ampliar o placar aberto por Arrascaeta ainda no primeiro tempo. N\u00e3o fez, tomou.<\/p>\n<p>Em Bragan\u00e7a, a derrocada tricolor, na verdade, come\u00e7ou e se ampliou por obra e gra\u00e7a daquela sa\u00edda de bola mal executada de h\u00e1bito pelos seus defensores. Na primeira, Dani Alves, como j\u00e1 ocorreu v\u00e1rias vezes, entregou a bola de bandeja pro advers\u00e1rio que n\u00e3o deixou barato. Na segunda, foi a vez de Diego tentar atrasar a bola pra Volpi.<\/p>\n<p>Mas, n\u00e3o foi s\u00f3 por isso que o S\u00e3o Paulo levou a goleada at\u00e9 piedosa pelas tantas chances desperdi\u00e7adas pelo advers\u00e1rio. Foi, sobretudo, m\u00e9rito do RB, muito bem distribu\u00eddo em campo, com um toque de bola primoroso, envolvente, muita determina\u00e7\u00e3o e extrema coragem ao enfrentar o l\u00edder do campeonato.<\/p>\n<p>Na tabela, ficaram elas por elas. Mas, e na alma dos jogadores do Fla e do S\u00e3o Paulo, o que restar\u00e1?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bem que o S\u00e3o Paulo deveria acender um milh\u00e3o de velas a seu padroeiro e demais santos e orix\u00e1s (como costumava dizer meu saudoso e <a class=\"read-more\" href=\"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/2021\/01\/06\/tricolor-agradeca-aos-ceus\/\">leia mais<\/a><\/p>\n","protected":false},"author":46,"featured_media":12295,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"jetpack_featured_media_url":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/files\/2021\/01\/5909_crop_galeria.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pekB7q-3ch","_links":{"self":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/posts\/12293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/comments?post=12293"}],"version-history":[{"count":0,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/posts\/12293\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/media\/12295"}],"wp:attachment":[{"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/media?parent=12293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/categories?post=12293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.gazetaesportiva.com\/albertohelena\/wp-json\/wp\/v2\/tags?post=12293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}